{"id":20680,"date":"2014-05-28T19:34:06","date_gmt":"2014-05-28T19:34:06","guid":{"rendered":"http:\/\/www.tvcnoticias.com.ar\/?p=20680"},"modified":"2014-05-28T19:34:06","modified_gmt":"2014-05-28T19:34:06","slug":"absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/","title":{"rendered":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES"},"content":{"rendered":"<p><a rel=\"attachment wp-att-20681\" href=\"http:\/\/www.tvcnoticias.com.ar\/?attachment_id=20681\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20681\" title=\"1461 - ABSA (Small)\" src=\"http:\/\/www.tvcnoticias.com.ar\/wp-content\/uploads\/2014\/05\/1461-ABSA-Small-450x311.jpg\" alt=\"\" width=\"450\" height=\"311\" \/><\/a>Respondiendo a gestiones efectuadas por el intendente municipal, licenciado Gustavo Trankels, directivos de la empresa ABSA SA visitaron la ciudad cabecera del distrito para comprobar el estado de la planta de tratamiento de efluentes l\u00edquidos cloacales y analizar los trabajos de mantenimiento que deben efectuarse en el lugar.<br \/>\nLa comitiva, que se reuni\u00f3 con el secretario de Gobierno y Hacienda, Guillermo L\u00f6ffler, y el subsecretario de Obras y Servicios P\u00fablicos, Christian Trankels, estuvo integrada por el gerente de Operaciones de la Regi\u00f3n 7 y 8, ingeniero Antonio Ferrara; el jefe de Operaciones Regional, ingeniero Gustavo Bentivegna; el responsable de proceso, licenciado qu\u00edmico Miguel Fambrini; y el responsable de la agencia local, ingeniero Carlos Quiroz.<br \/>\nDurante el encuentro, los representantes de ABSA se comprometieron a realizar los trabajos en la planta en cuesti\u00f3n, tarea por la cual recibir\u00e1n la colaboraci\u00f3n del Municipio.<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respondiendo a gestiones efectuadas por el intendente municipal, licenciado Gustavo Trankels, directivos de la empresa ABSA SA visitaron la ciudad cabecera del distrito para comprobar el estado de la planta de tratamiento de efluentes l\u00edquidos cloacales y analizar los trabajos de mantenimiento que deben efectuarse en el lugar. La comitiva, que se reuni\u00f3 con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52,53],"tags":[],"class_list":["post-20680","post","type-post","status-publish","format-standard","hentry","category-comunidad","category-destacadas","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-28T19:34:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.tvcnoticias.com.ar\/wp-content\/uploads\/2014\/05\/1461-ABSA-Small-450x311.jpg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES\",\"datePublished\":\"2014-05-28T19:34:06+00:00\",\"dateModified\":\"2014-05-28T19:34:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\"},\"wordCount\":160,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Comunidad\",\"Destacadas\",\"Pol\u00edtica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\",\"name\":\"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2014-05-28T19:34:06+00:00\",\"dateModified\":\"2014-05-28T19:34:06+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/","og_locale":"es_ES","og_type":"article","og_title":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2014-05-28T19:34:06+00:00","og_image":[{"url":"http:\/\/www.tvcnoticias.com.ar\/wp-content\/uploads\/2014\/05\/1461-ABSA-Small-450x311.jpg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES","datePublished":"2014-05-28T19:34:06+00:00","dateModified":"2014-05-28T19:34:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/"},"wordCount":160,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Comunidad","Destacadas","Pol\u00edtica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/","name":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2014-05-28T19:34:06+00:00","dateModified":"2014-05-28T19:34:06+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2014\/05\/28\/absa-se-comprometio-a-realizar-mantenimiento-en-la-planta-de-liquidos-cloacales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"ABSA. SE COMPROMETIO A REALIZAR MANTENIMIENTO EN LA PLANTA DE LIQUIDOS CLOACALES"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=20680"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/20680\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=20680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=20680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=20680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}