{"id":31559,"date":"2016-05-19T21:58:41","date_gmt":"2016-05-19T21:58:41","guid":{"rendered":"http:\/\/www.tvcnoticias.com.ar\/?p=31559"},"modified":"2016-05-19T21:58:41","modified_gmt":"2016-05-19T21:58:41","slug":"un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/","title":{"rendered":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)"},"content":{"rendered":"<p><a href='http:\/\/www.observadorserrano.com.ar\/shop\/detallenot.asp?notid=1170' > Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)<\/a><\/p>\n<p><a href=\"http:\/\/www.tvcnoticias.com.ar\/?attachment_id=31560\" rel=\"attachment wp-att-31560\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2016\/05\/DSC_5679-Small.jpg\" alt=\"\" title=\"DSC_5679 (Small)\" width=\"720\" height=\"480\" class=\"alignleft size-full wp-image-31560\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2016\/05\/DSC_5679-Small.jpg 720w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2016\/05\/DSC_5679-Small-300x200.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,61],"tags":[],"class_list":["post-31559","post","type-post","status-publish","format-standard","hentry","category-destacadas","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-19T21:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2016\/05\/DSC_5679-Small.jpg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)\",\"datePublished\":\"2016-05-19T21:58:41+00:00\",\"dateModified\":\"2016-05-19T21:58:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\"},\"wordCount\":34,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Destacadas\",\"Policiales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\",\"name\":\"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2016-05-19T21:58:41+00:00\",\"dateModified\":\"2016-05-19T21:58:41+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/","og_locale":"es_ES","og_type":"article","og_title":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2016-05-19T21:58:41+00:00","og_image":[{"url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2016\/05\/DSC_5679-Small.jpg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)","datePublished":"2016-05-19T21:58:41+00:00","dateModified":"2016-05-19T21:58:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/"},"wordCount":34,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Destacadas","Policiales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/","name":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video) - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2016-05-19T21:58:41+00:00","dateModified":"2016-05-19T21:58:41+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2016\/05\/19\/un-camion-volco-al-caer-en-una-trampa-en-la-ruta-33-agrega-imagenes-en-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Un cami\u00f3n volc\u00f3 al caer en una \u201ctrampa\u201d en la ruta 33 (Agrega im\u00e1genes en video)"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=31559"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/31559\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=31559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=31559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=31559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}