{"id":38037,"date":"2018-10-17T18:13:01","date_gmt":"2018-10-17T18:13:01","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=38037"},"modified":"2018-10-17T18:13:01","modified_gmt":"2018-10-17T18:13:01","slug":"la-obra-encuentros-se-presentara-en-el-teatro-municipal","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/","title":{"rendered":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal"},"content":{"rendered":"<p>\u201c<strong>ENCUENTROS\u201d, <\/strong>un espect\u00e1culo de teatro musical, se presentar\u00e1 en el teatro municipal \u201cRodolfo Funke\u201d el VIERNES 26 del corriente mes, a las 21.00 hs.<br \/>\nLa obra incluye solos y d\u00faos para corno y bandone\u00f3n que se tocar\u00e1n en<br \/>\nvivo, y tres temas para cuarteto\/quinteto (viol\u00edn, piano, bandone\u00f3n, contrabajo, vibr\u00e1fono) grabados en un estudio.<br \/>\nLa particularidad de esta obra de teatro es que no tiene texto y que cada uno de los artistas en escena encarna un personaje.<br \/>\nToda la obra es un estreno, tanto la historia como tambi\u00e9n la m\u00fasica y la<br \/>\ncoreograf\u00eda.<br \/>\n&nbsp;<br \/>\nEl espect\u00e1culo recibi\u00f3 el apoyo del Fondo Municipal de las Artes y del Fondo Nacional de las Artes.<br \/>\nM\u00fasica original de Gustavo Beytelmann.<br \/>\nHISTORIA<br \/>\nEl encuentro de un joven marionetista ingenioso con un bandoneonista lunar y a una cornista ladrona.<br \/>\nTras el encuentro de estos tres personajes, se agregar\u00e1 una marioneta que cobrar\u00e1 vida al sonido de dos instrumentos y se metamorfosear\u00e1 con los rasgos de una mujer.<br \/>\nEstos encuentros har\u00e1n resonar en ellos cuestionamientos existenciales sobre su forma de vincularse con la vida y con los otros.\u00a0Su aventura los conducir\u00e1 a Argentina al encuentro del amor, de sus sue\u00f1os, del tango y de un \u00e1rbol de deseos juguet\u00f3n.<br \/>\nUn viaje en b\u00fasqueda de identidad.<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cENCUENTROS\u201d, un espect\u00e1culo de teatro musical, se presentar\u00e1 en el teatro municipal \u201cRodolfo Funke\u201d el VIERNES 26 del corriente mes, a las 21.00 hs. La obra incluye solos y d\u00faos para corno y bandone\u00f3n que se tocar\u00e1n en vivo, y tres temas para cuarteto\/quinteto (viol\u00edn, piano, bandone\u00f3n, contrabajo, vibr\u00e1fono) grabados en un estudio. La particularidad [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38038,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,56],"tags":[],"class_list":["post-38037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-espectaculos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-17T18:13:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/10\/DSC_7375.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2508\" \/>\n\t<meta property=\"og:image:height\" content=\"1666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal\",\"datePublished\":\"2018-10-17T18:13:01+00:00\",\"dateModified\":\"2018-10-17T18:13:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Espect\u00e1culos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\",\"name\":\"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2018-10-17T18:13:01+00:00\",\"dateModified\":\"2018-10-17T18:13:01+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/","og_locale":"es_ES","og_type":"article","og_title":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2018-10-17T18:13:01+00:00","og_image":[{"width":2508,"height":1666,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/10\/DSC_7375.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal","datePublished":"2018-10-17T18:13:01+00:00","dateModified":"2018-10-17T18:13:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/"},"wordCount":236,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Espect\u00e1culos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/","name":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2018-10-17T18:13:01+00:00","dateModified":"2018-10-17T18:13:01+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/10\/17\/la-obra-encuentros-se-presentara-en-el-teatro-municipal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"La obra \u201cENCUENTROS\u201d se presentar\u00e1 en el teatro municipal"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=38037"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/38038"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=38037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=38037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=38037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}