{"id":38392,"date":"2018-11-07T20:10:58","date_gmt":"2018-11-07T20:10:58","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=38392"},"modified":"2018-11-07T20:10:58","modified_gmt":"2018-11-07T20:10:58","slug":"una-imagen-que-vale-mas-que-mil-palabras","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/","title":{"rendered":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Sobre la gesti\u00f3n de CAMBIEMOS y su jefe comunal Sergio Bordoni.<\/strong><\/p>\n<p style=\"font-weight: 400;\">La imagen que acompa\u00f1a este comunicado desea expresar mil palabras que describir\u00edan lo que fue y es la gesti\u00f3n de CAMBIEMOS a nivel nacional y provincial, y en particular del intendente Sergio Bordoni en el distrito de Tornquist. Lo que observamos es un m\u00f3vil del municipio que hace unos d\u00edas transit\u00f3 a 130 o 140 kil\u00f3metros por hora y pas\u00f3 numerosos veh\u00edculos -hasta a un cami\u00f3n- en presencia de doble l\u00ednea amarilla y en una curva. Si manejamos las cosas sin cuidado y sin control, si hacemos caso omiso a las indicaciones de los que pueden y quieren aportarnos soluciones seguro los resultados ser\u00e1n los que estamos obteniendo.<\/p>\n<p style=\"font-weight: 400;\">Si nos manejamos como conducimos el m\u00f3vil municipal que acompa\u00f1a este comunicado los resultados ser\u00e1n muy negativos para todos los ciudadanos del distrito. La ausencia de una planificaci\u00f3n integral y una ordenada administraci\u00f3n municipal se evidencia en muchas realidades.<\/p>\n<p style=\"font-weight: 400;\">Elegimos usar una imagen porque de palabras seguro estamos cansados, como tambi\u00e9n estamos cansados de las excusas continuamente utilizadas por el actual jefe comunal cuando las cosas no le salen bien. Est\u00e1 claro que el distrito est\u00e1 olvidado y abandonado en el escenario de las decisiones p\u00fablicas del gobierno nacional y provincial, y en lo local el plan de gobierno se encuentra muy desarticulado y con marchas y contramarchas que nos perjudican a todos. Otros distritos de similares caracter\u00edsticas que Tornquist \u2013a\u00fan gobernados por la oposici\u00f3n a CAMBIEMOS- tienen mejor gesti\u00f3n y relaci\u00f3n con el gobierno provincial y nacional.<\/p>\n<p style=\"font-weight: 400;\">Nosotros pensamos otro presente y otro futuro para el distrito por eso no somos parte de CAMBIEMOS ni del gobierno municipal. Siempre hemos tenido en cuenta la decisi\u00f3n de las mayor\u00edas y esto se ha reflejado, entre otras cosas, en la constante actitud constructiva que desarrollamos en los temas en los cuales hemos trabajado para mejorar nuestra casa com\u00fan llamada distrito de Tornquist.<\/p>\n<p style=\"font-weight: 400;\">Compartiendo el diagn\u00f3stico que usted hace sobre la situaci\u00f3n angustiante de las \u201cclases medias y bajas\u201d, no creemos que haya en su administraci\u00f3n una intenci\u00f3n real de buscar una soluci\u00f3n al problema enunciado porque, de existir esta intenci\u00f3n, podr\u00eda entre otras cosas estar llamando con urgencia a la conformaci\u00f3n de una mesa multisectorial para poner en marcha un plan de contingencia al que todos aporten las mejores ideas para aliviar a los \u201cm\u00e1s castigado con estos aumentos en los combustibles, que afectan directamente y se trasladan a los alimentos\u201d; o podr\u00eda, cuando se discute el presupuesto nacional y provincial, unir la mayor cantidad de voluntades pol\u00edticas para desarrollar acciones de real incidencia en los centros de decisi\u00f3n que adem\u00e1s son de su mismo color pol\u00edtico.<\/p>\n<p style=\"font-weight: 400;\">Ojala nuestro jefe comunal mida estas palabras con la sensatez que debe tener la m\u00e1xima autoridad del distrito y no como ha hecho hasta ahora cuando -ante nuestros aportes- \u00a0solo ha tenido descalificaciones y destratos. Ojal\u00e1 todos los dirigentes pol\u00edticos del distrito usemos nuestra energ\u00eda en trabajar para que los tornquinstenses estemos mejor y que el distrito crezca y se desarrolle.<\/p>\n<p style=\"font-weight: 400;\">El intendente Bordoni est\u00e1 al mando de este m\u00f3vil que se llama Municipio de Tornquist y creemos, que a la manera de la imagen, el actual jefe comunal tiene una responsabilidad p\u00fablica enorme; por lo tanto le solicitamos, recapacite y haga las correcciones que tenga que hacer, comenzando por el gobierno local que es el lugar donde m\u00e1s le corresponde.<\/p>\n<p style=\"font-weight: 400;\">Unidad Ciudadana Tornquist<\/p>\n<div id='gallery_1' class='gallery galleryid-38392 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/AUTO-2.png'><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"196\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/AUTO-2.png\" data-sizes=\"auto\" data-srcset=\"\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"179\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1-300x179.png\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1-300x179.png 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1.png 354w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-y-curva.png'><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"196\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-y-curva.png\" data-sizes=\"auto\" data-srcset=\"\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><br style=\"clear: both\" \/><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla.png'><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"196\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla.png\" data-sizes=\"auto\" data-srcset=\"\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-va-a-pasar-un-auto-y-u-n-cami\u00a6n-en-doble-li-nea-amarilla-y-curva.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"127\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-va-a-pasar-un-auto-y-u-n-cami\u00a6n-en-doble-li-nea-amarilla-y-curva-300x127.png\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-va-a-pasar-un-auto-y-u-n-cami\u00a6n-en-doble-li-nea-amarilla-y-curva-300x127.png 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-va-a-pasar-un-auto-y-u-n-cami\u00a6n-en-doble-li-nea-amarilla-y-curva.png 410w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure>\n            <br style='clear: both' \/>\n        <\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Sobre la gesti\u00f3n de CAMBIEMOS y su jefe comunal Sergio Bordoni. La imagen que acompa\u00f1a este comunicado desea expresar mil palabras que describir\u00edan lo que fue y es la gesti\u00f3n de CAMBIEMOS a nivel nacional y provincial, y en particular del intendente Sergio Bordoni en el distrito de Tornquist. Lo que observamos es un m\u00f3vil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38395,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52],"tags":[],"class_list":["post-38392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-07T20:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"354\" \/>\n\t<meta property=\"og:image:height\" content=\"211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS\",\"datePublished\":\"2018-11-07T20:10:58+00:00\",\"dateModified\":\"2018-11-07T20:10:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\"},\"wordCount\":630,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Comunidad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\",\"name\":\"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2018-11-07T20:10:58+00:00\",\"dateModified\":\"2018-11-07T20:10:58+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2018-11-07T20:10:58+00:00","og_image":[{"width":354,"height":211,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2018\/11\/movil-oficial-pasando-un-auto-en-doble-linea-amarilla-1.png","type":"image\/png"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS","datePublished":"2018-11-07T20:10:58+00:00","dateModified":"2018-11-07T20:10:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/"},"wordCount":630,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Comunidad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/","name":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2018-11-07T20:10:58+00:00","dateModified":"2018-11-07T20:10:58+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2018\/11\/07\/una-imagen-que-vale-mas-que-mil-palabras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Comunicado de Unidad Ciudadana Tornquist :UNA IMAGEN QUE VALE MAS QUE MIL PALABRAS"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=38392"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/38392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/38395"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=38392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=38392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=38392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}