{"id":42040,"date":"2019-06-08T22:26:29","date_gmt":"2019-06-08T22:26:29","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=42040"},"modified":"2019-06-08T22:26:29","modified_gmt":"2019-06-08T22:26:29","slug":"torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/","title":{"rendered":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina"},"content":{"rendered":"<p>Villa Mitre venci\u00f3 este\u00a0viernes\u00a0a Z\u00e1rate Basket por el tercer punto de las semifinales del Torneo Federal de B\u00e1squetbol y ascendi\u00f3 a la Liga Argentina, segundo escal\u00f3n en la pir\u00e1mide del b\u00e1squetbol nacional.<\/p>\n<p>El tricolor se impuso como visitante, por 94 a 87 en suplementario, luego de igualar en 77 en el tiempo regular y cerr\u00f3 la llave como visitante.<\/p>\n<p><strong><a href=\"https:\/\/www.fibalivestats.com\/u\/CAM\/1184554\/bs.html\" target=\"_blank\" rel=\"noopener\">Mir\u00e1 las estad\u00edsticas del partido<\/a><\/strong><\/p>\n<p>De esta manera, la &#8220;Villa&#8221; barri\u00f3 la serie por 3 a 0 y jugar\u00e1 la final, en busca del t\u00edtulo, aunque con el ascenso ya asegurado.<\/p>\n<p><strong><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/TWLina9dsH0\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/strong><\/p>\n<p>Salvo por un pasaje del primer cuarto, en el que la visita pudo alejarse 21-13 con parcial de 10-0, en adelante fue un partido de pocas ventajas y reparto en el cambio de marcador.<\/p>\n<p>El due\u00f1o de casa inici\u00f3 el encuentro sabiendo que no contar\u00eda con el alero Dami\u00e1n Pineda, quien en el entrenamiento de la noche previa sinti\u00f3 fuerte dolor en la zona lumbar. Una baja fundamental por su liderazgo y frente al regreso de Facundo Barretto.<\/p>\n<p>Z\u00e1rate pudo controlar a Villa Mitre en los momentos que el elenco verde tuvo que darle descanso a Jos\u00e9 Guti\u00e9rrez (fisura en una v\u00e9rtebra) o bien cuando sali\u00f3 Franco Pennacchiotti. Sin embargo, con un acierto de 3, Franco Amigo llev\u00f3 a los suyos a sacar 10 de ventaja. El alero comenzaba a dar se\u00f1ales de que ser\u00eda una carta importante para los dirigidos por Ariel Ugolini.<\/p>\n<p>Pero el local, que control\u00f3 bien a Federico Harina con el bahiense Facundo Pascolatt, revivi\u00f3 con Exequiel Cassinelli y descont\u00f3 de cara al segundo tiempo (37-33 los 20 iniciales en favor de la visita).<\/p>\n<p>En el tercero los orientados por Guillermo Bogliacino se mantuvieron firmes en defensa -Pennacchiotti hab\u00eda sumado tan s\u00f3lo 4 puntos en la primera etapa-\u00a0 y pasaron al frente con doble de Guillermo Gavotti (44-43), ante un rival perdido y sin una v\u00eda clara de gol.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/px.cdn.lanueva.com\/062019\/1559976499146\/VillaFeste3.jpeg\" width=\"100%\" height=\"auto\" \/>El equipo tricolor, posando &#8220;en modo osoo&#8221; tras decretar el 3-0 en la serie.<\/p>\n<p>Conscientes del paso del tiempo, ambos equipos comenzaron a arriesgar un poco m\u00e1s. Patricio Aranda se volvi\u00f3 imparable desde los 6m75 para la defensa bahiense (2-3\u00a0en triples en el parcial), acompa\u00f1ado por Cassinelli y para ganar un per\u00edodo de gol elevado (27 puntos). En el peor momento visitante, Jos\u00e9 Guti\u00e9rrez asumi\u00f3 el liderazgo ofensivo con ataques profundos (8 puntos), complementado por los triples de Amigo (2-2) para continuar en partido de cara al \u00faltimo cuarto.<\/p>\n<p>Que mostr\u00f3 mejor a Villa Mitre. Con un Ramiro Heinrich m\u00e1s determinante (7 puntos) en la lucha en poste bajo ante la marca de Aranda. Mientras que el local sosten\u00eda su ilusi\u00f3n con m\u00e1s triples de Aranda (3-3) pero muy en solitario respecto de los dem\u00e1s.<\/p>\n<p>Un triple de Cassinelli con bastante tiempo por delante (2m14) acomod\u00f3 mejor a Z\u00e1rate de cara al cierre (77-74). Pero Heinrich persisti\u00f3 abajo y concret\u00f3 un doble (77-76) m\u00e1s 1-2 en simples que igualaron el partido en 77. A Cassinelli le qued\u00f3 la \u00faltima del tiempo regular -como en el juego 2- pero su lanzamiento desde un costado no entr\u00f3.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/5iDnkMFAx6U\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>En el suplementario arranc\u00f3 con mejor imagen defensiva Villa Mitre. Y frente a los yerros del local (Aranda y Pascolatt combinaron 1-5\u00a0en triples), respondi\u00f3 con juego colectivo: un doble+falta convertidos por Amigo (81-77 a 3m11s), dos libres de Harina (83-80 a 2m33s), 4 puntos de Pennacchiotti (87-84 a 1m23s) y un acierto de 3 decisivo de Harina (90-84 a 44s).<\/p>\n<p>En el per\u00edodo adicional, Villa Mitre cambi\u00f3 la cara en un partido delicado y se qued\u00f3 con el premio mayor.<\/p>\n<p>FUENTE: LA NUEVA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Villa Mitre venci\u00f3 este\u00a0viernes\u00a0a Z\u00e1rate Basket por el tercer punto de las semifinales del Torneo Federal de B\u00e1squetbol y ascendi\u00f3 a la Liga Argentina, segundo escal\u00f3n en la pir\u00e1mide del b\u00e1squetbol nacional. El tricolor se impuso como visitante, por 94 a 87 en suplementario, luego de igualar en 77 en el tiempo regular y cerr\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42041,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,60,52,63],"tags":[],"class_list":["post-42040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-deporte","category-destacadas","category-magazine-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-08T22:26:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/06\/1559973548800.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina\",\"datePublished\":\"2019-06-08T22:26:29+00:00\",\"dateModified\":\"2019-06-08T22:26:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\"},\"wordCount\":634,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Deporte\",\"Destacadas\",\"Magazine Sport\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\",\"name\":\"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2019-06-08T22:26:29+00:00\",\"dateModified\":\"2019-06-08T22:26:29+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2019-06-08T22:26:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/06\/1559973548800.jpeg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina","datePublished":"2019-06-08T22:26:29+00:00","dateModified":"2019-06-08T22:26:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/"},"wordCount":634,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Deporte","Destacadas","Magazine Sport"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/","name":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2019-06-08T22:26:29+00:00","dateModified":"2019-06-08T22:26:29+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/06\/08\/torneo-federal-villa-mitre-vencio-a-zarate-basket-en-suplementario-y-ascendio-a-la-liga-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Villa Mitre con Ramiro Heinrich en cancha, venci\u00f3 a Z\u00e1rate Basket en suplementario y ascendi\u00f3 a la Liga Argentina"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/42040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=42040"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/42040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/42041"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=42040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=42040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=42040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}