{"id":44571,"date":"2019-10-10T12:54:06","date_gmt":"2019-10-10T12:54:06","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=44571"},"modified":"2019-10-10T12:54:06","modified_gmt":"2019-10-10T12:54:06","slug":"ampliacion-de-750mts-de-desagues-cloacales-en-tornquist","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/","title":{"rendered":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist"},"content":{"rendered":"<p>La Secretar\u00eda de Obras y Servicios P\u00fablicos informa que contin\u00faan las tareas de extensi\u00f3n de la red cloacal en la ciudad de Tornquist, obra que beneficiara directamente a los vecinos.<\/p>\n<p>La extensi\u00f3n del sistema de desag\u00fces cloacales, de 750mts de red, se ejecutar\u00e1 en las calles Lavalle entre Int. Ruppel y Col\u00f3n (Manzana 104), Espa\u00f1a entre de los Inmigrantes y Lamela, Ameghino entre J.M de Rosas y Ruppel (Manzana 125), J.M de Rosas entre R. de Tornquist y Ameghino (Manzana 125), y Col\u00f3n entre Rawson e Irigoyen (Manzana 179).<\/p>\n<p>El plan de ampliaci\u00f3n comenz\u00f3 en el mes de enero, en donde se provey\u00f3 de desag\u00fces cloacales las calles Independencia entre\u00a0 12 de Octubre y Rawson (Manzana 165), Gral. Paz entre Scharff y Col\u00f3n (Manzana 147), y continu\u00f3 en el mes de septiembre sobre Sarmiento entre Filiberto y Quinquela Mart\u00edn.<\/p>\n<p>La obra, est\u00e1 enmarcada dentro del convenio de colaboraci\u00f3n, firmado entre el municipio y la empresa ABSA, a trav\u00e9s del cual, la misma se compromete aportar los materiales necesarios para ejecutar las tareas.<\/p>\n<p>Es importante destacar, que estas obras, forman parte de un plan integral de saneamiento urbano, y tiene como finalidad garantizar la conexi\u00f3n a los vecinos de la ciudad cabecera, su tratamiento, y por sobretodo evitar el impacto que producen este tipo de aguas en el medio ambiente, y el entorno social.<\/p>\n<p><a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=44572\" rel=\"attachment wp-att-44572\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-44572\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46.jpeg\" alt=\"\" width=\"960\" height=\"1280\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46.jpeg 960w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46-225x300.jpeg 225w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46-768x1024.jpeg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46-750x1000.jpeg 750w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a> <a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=44573\" rel=\"attachment wp-att-44573\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-44573\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48.jpeg\" alt=\"\" width=\"780\" height=\"585\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48.jpeg 1280w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48-300x225.jpeg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48-1024x768.jpeg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48-768x576.jpeg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48-750x563.jpeg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.48-1140x855.jpeg 1140w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Obras y Servicios P\u00fablicos informa que contin\u00faan las tareas de extensi\u00f3n de la red cloacal en la ciudad de Tornquist, obra que beneficiara directamente a los vecinos. La extensi\u00f3n del sistema de desag\u00fces cloacales, de 750mts de red, se ejecutar\u00e1 en las calles Lavalle entre Int. Ruppel y Col\u00f3n (Manzana 104), Espa\u00f1a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,52],"tags":[],"class_list":["post-44571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-10T12:54:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist\",\"datePublished\":\"2019-10-10T12:54:06+00:00\",\"dateModified\":\"2019-10-10T12:54:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\",\"name\":\"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2019-10-10T12:54:06+00:00\",\"dateModified\":\"2019-10-10T12:54:06+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/","og_locale":"es_ES","og_type":"article","og_title":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2019-10-10T12:54:06+00:00","og_image":[{"width":960,"height":1280,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/10\/WhatsApp-Image-2019-10-09-at-10.03.46.jpeg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist","datePublished":"2019-10-10T12:54:06+00:00","dateModified":"2019-10-10T12:54:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/"},"wordCount":244,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/","name":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2019-10-10T12:54:06+00:00","dateModified":"2019-10-10T12:54:06+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/10\/10\/ampliacion-de-750mts-de-desagues-cloacales-en-tornquist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Ampliaci\u00f3n de 750mts de desag\u00fces cloacales en Tornquist"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/44571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=44571"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/44571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/44572"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=44571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=44571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=44571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}