{"id":45234,"date":"2019-11-07T15:20:38","date_gmt":"2019-11-07T15:20:38","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=45234"},"modified":"2019-11-07T15:20:38","modified_gmt":"2019-11-07T15:20:38","slug":"atropellan-a-una-persona-en-el-centro-de-la-ciudad","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/","title":{"rendered":"\u00a0Atropellan a una persona en el centro de la ciudad"},"content":{"rendered":"<div style=\"color: #000000; font-family: Arial, Verdana, sans-serif; font-size: 12px;\">Ocurri\u00f3 esta ma\u00f1ana alrededor de\u00a0 las 11,10 hs. en la intersecci\u00f3n de 9 de Julio y Mitre de nuestra ciudad.<\/div>\n<div style=\"color: #000000; font-family: Arial, Verdana, sans-serif; font-size: 12px;\">La ciudadana Yanina Canale (27) con domicilio en Irigoyen 309 de nuestra ciudad, habr\u00eda sido colisionada por un autom\u00f3vil\u00a0 Renault Logan dominio JJS650 conducido por Susana Alcira Catani (69) domiciliada en Guemes 179.<\/div>\n<div style=\"color: #000000; font-family: Arial, Verdana, sans-serif; font-size: 12px;\">El autom\u00f3vil circulaba por calle Mitre para retomar la avda. 9 de Julio.<\/div>\n<div style=\"color: #000000; font-family: Arial, Verdana, sans-serif; font-size: 12px;\">A los pocos minutos se hizo presente en el lugar una ambulancia del SAME Tornquist que traslad\u00f3 a Canale, por precauci\u00f3n, al nosocomio local, personal policial y del cuerpo de inspectores Municipales.<\/div>\n<div style=\"color: #000000; font-family: Arial, Verdana, sans-serif; font-size: 12px;\">Por espacio de varios minutos se interrumpi\u00f3 el transito sobre la segunda y tercera cuadra de 9 de Julio de este a oeste.<\/div>\n<div><\/div>\n<div>\n<div id='gallery_1' class='gallery galleryid-45234 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n            <div class='gallery-icon portrait'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/6323a9f7-f108-414a-be13-b14fd53692df.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/6323a9f7-f108-414a-be13-b14fd53692df-169x300.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/6323a9f7-f108-414a-be13-b14fd53692df-169x300.jpg 169w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/6323a9f7-f108-414a-be13-b14fd53692df-576x1024.jpg 576w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/6323a9f7-f108-414a-be13-b14fd53692df.jpg 581w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597-300x169.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597-300x169.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597-1024x576.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597-768x432.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597-750x422.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/7775f0bd-cb3f-41b1-86a2-667c8f9ee597.jpg 1032w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab-300x169.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab-300x169.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab-1024x576.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab-768x432.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab-750x422.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/8873cd01-52e6-4e9b-bce0-3154a72aaeab.jpg 1032w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure><br style=\"clear: both\" \/><figure class='gallery-item'>\n            <div class='gallery-icon landscape'>\n                <a href='https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"\" class=\"attachment-medium size-medium lazyload\" alt=\"\" data-src=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741-300x169.jpg\" data-sizes=\"auto\" data-srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741-300x169.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741-1024x576.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741-768x432.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741-750x422.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741.jpg 1032w\" data-expand=\"700\" \/><\/a>\n            <\/div><\/figure>\n            <br style='clear: both' \/>\n        <\/div>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ocurri\u00f3 esta ma\u00f1ana alrededor de\u00a0 las 11,10 hs. en la intersecci\u00f3n de 9 de Julio y Mitre de nuestra ciudad. La ciudadana Yanina Canale (27) con domicilio en Irigoyen 309 de nuestra ciudad, habr\u00eda sido colisionada por un autom\u00f3vil\u00a0 Renault Logan dominio JJS650 conducido por Susana Alcira Catani (69) domiciliada en Guemes 179. El autom\u00f3vil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45242,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,61],"tags":[],"class_list":["post-45234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-07T15:20:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1032\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"\u00a0Atropellan a una persona en el centro de la ciudad\",\"datePublished\":\"2019-11-07T15:20:38+00:00\",\"dateModified\":\"2019-11-07T15:20:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\"},\"wordCount\":133,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Espect\u00e1culos\",\"Policiales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\",\"name\":\"\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2019-11-07T15:20:38+00:00\",\"dateModified\":\"2019-11-07T15:20:38+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0Atropellan a una persona en el centro de la ciudad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2019-11-07T15:20:38+00:00","og_image":[{"width":1032,"height":581,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2019\/11\/a39e49e3-0906-4517-9481-e5ae84b07741.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"\u00a0Atropellan a una persona en el centro de la ciudad","datePublished":"2019-11-07T15:20:38+00:00","dateModified":"2019-11-07T15:20:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/"},"wordCount":133,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Espect\u00e1culos","Policiales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/","name":"\u00a0Atropellan a una persona en el centro de la ciudad - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2019-11-07T15:20:38+00:00","dateModified":"2019-11-07T15:20:38+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2019\/11\/07\/atropellan-a-una-persona-en-el-centro-de-la-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"\u00a0Atropellan a una persona en el centro de la ciudad"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/45234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=45234"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/45234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/45242"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=45234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=45234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=45234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}