{"id":47302,"date":"2020-02-19T12:48:05","date_gmt":"2020-02-19T12:48:05","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=47302"},"modified":"2020-02-19T12:48:05","modified_gmt":"2020-02-19T12:48:05","slug":"secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/","title":{"rendered":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES"},"content":{"rendered":"<p style=\"font-weight: 400;\">Desde la Secretaria de Seguridad de la Municipalidad de Tornquist, llevamos a conocimiento de la poblaci\u00f3n lo ocurrido en los \u00faltimos d\u00edas, referente a hechos y operativos policiales que se detallan a continuaci\u00f3n:<\/p>\n<p style=\"font-weight: 400;\"><strong>SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Se informa que en el d\u00eda de la fecha (martes 18), personal policial de la Estaci\u00f3n Comunal de Tornquist, procedi\u00f3 a la identificaci\u00f3n de una pareja for\u00e1nea del medio, trat\u00e1ndose de Marcelo N\u00e9stor Mart\u00ednez, de 36 a\u00f1os, y su pareja Priscila Natalie Torrisi M\u00e9ndez, de 24 a\u00f1os, ambos oriundos de San Carlos de Bariloche, quienes circulaban a bordo de una camioneta Ford Ranger, dominio IKR-191, y al ser cursado los datos filiatorios de la pareja, como as\u00ed el dominio del rodado por Sala Inform\u00e1tica de la Polic\u00eda, se constata que el veh\u00edculo ten\u00eda un\u00a0<strong>PEDIDO DE SECUESTRO<\/strong>\u00a0<strong>ACTIVO<\/strong>solicitado por el Ministerio P\u00fablico Fiscal de la ciudad de Comodoro Rivadavia por el delito de\u00a0<strong>ESTAFA,\u00a0<\/strong>por lo que el veh\u00edculo qued\u00f3 secuestrado en la seccional policial local, a disposici\u00f3n del magistrado interviniente.-<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><strong>INFRACCION A LA LEY DE ESTUPEFACIONES N\u00ba 23.737.-<\/strong><\/p>\n<p style=\"font-weight: 400;\">Con fecha 17\/2\/2020, sobre intersecci\u00f3n de calles Corrales y Rinc\u00f3n de Saldungaray, personal policial de la Sub Estaci\u00f3n Policial de dicha localidad procedi\u00f3 a la detenci\u00f3n del joven\u00a0<strong>NAHUEL YAIR TORRES,<\/strong>\u00a0de 20 a\u00f1os de edad, oriundo de Bah\u00eda Blanca, quien fuera sorprendido por los uniformados al momento de requis\u00e1rsele sus pertenec\u00edas, con un tubo met\u00e1lico curvo de unos 10 cm, utilizado com\u00fanmente como pipa \u2013 tuquera-, conteniendo en su interior picadillo de una sustancia verdosa tipo yerba que llevaba en su poder, y que posteriormente, realizado el test de orientaci\u00f3n en reactivos el mismo, dio\u00a0<strong>POSITIVO\u00a0<\/strong>para marihuana, arrojando un pesaje total de 2 gramos. Se procedi\u00f3 al decomiso de la sustancia. Interviene la Unidad Funcional de Instrucci\u00f3n y Juicio Nro. 19 (especializada en delitos de estupefacientes) del Departamento Judicial Bah\u00eda Blanca. El joven Torres, luego de realizar los recaudos legales pertinentes, recuper\u00f3 su LIBERTAD.-<\/p>\n<p style=\"font-weight: 400;\">Por otro lado, \u00a0dicho d\u00eda en momentos en que el m\u00f3vil policial de la mencionada seccional se encontraba recorriendo el Balneario Municipal de Saldungaray, puede divisar entre la vegetaci\u00f3n dos plantas similares en caracter\u00edsticas y contextura a la de Marihuana, procediendo a su secuestro, arrojando un resultado total de 170 gramos en pesaje, y\u00a0<strong>POSITIVO para Marihuana<\/strong>\u00a0en su test de orientaci\u00f3n en reactivos, labr\u00e1ndose Actuaciones Prevencionales por Infracci\u00f3n a la Ley Federal de Estupefacientes N\u00ba 23.737, con intervenci\u00f3n de la Ufij N\u00ba 19 de Bah\u00eda Blanca.-<\/p>\n<p style=\"font-weight: 400;\"><strong>SECRETARIA DE SEGURIDAD \u2013 MUNICIPALIDAD DE TORNQUIST<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>18 DE FEBRERO DE 2020.-<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=47306\" rel=\"attachment wp-att-47306\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-47306\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/CAMIO-1.png\" alt=\"\" width=\"586\" height=\"430\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/CAMIO-1.png 586w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/CAMIO-1-300x220.png 300w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/a> <a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=47307\" rel=\"attachment wp-att-47307\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-47307\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/Imagen1-Medium.png\" alt=\"\" width=\"666\" height=\"780\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/Imagen1-Medium.png 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/Imagen1-Medium-256x300.png 256w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/Imagen1-Medium-750x879.png 750w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/a> <a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=47308\" rel=\"attachment wp-att-47308\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-47308\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium.png\" alt=\"\" width=\"780\" height=\"533\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium.png 1124w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium-300x205.png 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium-1024x700.png 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium-768x525.png 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/p-Medium-750x512.png 750w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Secretaria de Seguridad de la Municipalidad de Tornquist, llevamos a conocimiento de la poblaci\u00f3n lo ocurrido en los \u00faltimos d\u00edas, referente a hechos y operativos policiales que se detallan a continuaci\u00f3n: SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA \u00a0Se informa que en el d\u00eda de la fecha (martes 18), personal policial de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52,61],"tags":[],"class_list":["post-47302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-destacadas","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T12:48:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/CAMIO.png\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES\",\"datePublished\":\"2020-02-19T12:48:05+00:00\",\"dateModified\":\"2020-02-19T12:48:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Comunidad\",\"Destacadas\",\"Policiales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\",\"name\":\"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2020-02-19T12:48:05+00:00\",\"dateModified\":\"2020-02-19T12:48:05+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/","og_locale":"es_ES","og_type":"article","og_title":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2020-02-19T12:48:05+00:00","og_image":[{"width":586,"height":430,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/02\/CAMIO.png","type":"image\/png"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES","datePublished":"2020-02-19T12:48:05+00:00","dateModified":"2020-02-19T12:48:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/"},"wordCount":474,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Comunidad","Destacadas","Policiales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/","name":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2020-02-19T12:48:05+00:00","dateModified":"2020-02-19T12:48:05+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/02\/19\/secuestro-de-vehiculo-por-el-delito-de-estafa-e-infraccion-a-la-ley-no-23-737-de-estupefacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"SECUESTRO DE VEHICULO POR EL DELITO DE ESTAFA E INFRACCION A LA LEY N\u00ba 23.737 DE ESTUPEFACIENTES"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=47302"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/47302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/47304"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=47302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=47302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=47302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}