{"id":49314,"date":"2020-05-28T16:53:46","date_gmt":"2020-05-28T16:53:46","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=49314"},"modified":"2020-05-28T16:53:46","modified_gmt":"2020-05-28T16:53:46","slug":"arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/","title":{"rendered":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses"},"content":{"rendered":"<p style=\"font-weight: 400;\">La Agencia de Recaudaci\u00f3n de la provincia de Buenos Aires extendi\u00f3 hasta el\u00a0<strong>31 de julio pr\u00f3ximo<\/strong>\u00a0la vigencia del plan de regularizaci\u00f3n de deudas destinado a micro, peque\u00f1as y medianas empresas, que venc\u00eda el 31 de mayo.<\/p>\n<p style=\"font-weight: 400;\">El programa de facilidades, que contempla la quita total de intereses, multas y punitorios, abarca deudas vencidas al 31 de diciembre de 2019 \u2014tanto en estado judicial como prejudicial\u2014, planes de pago caducos y vigentes. Comprende a los impuestos Inmobiliario, B\u00e1sico y Complementario; Automotores; Ingresos Brutos y Sellos.<\/p>\n<p style=\"font-weight: 400;\">Los beneficios son importantes, a punto tal que en algunos casos la condonaci\u00f3n puede alcanzar el 70% del monto total adeudado. El plan permite pagar en un plazo de hasta 10 a\u00f1os \u2014120 cuotas\u2014 con un inter\u00e9s fijo, o bien en 3 cuotas sin intereses de financiaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">En el caso de los contribuyentes que posean deuda en instancia judicial, tambi\u00e9n prev\u00e9 el levantamiento autom\u00e1tico de los embargos con la sola adhesi\u00f3n al programa.<\/p>\n<p style=\"font-weight: 400;\">La suscripci\u00f3n se realiza por internet y los beneficios se encuentran segmentados de manera progresiva por tama\u00f1o y tipo de empresa, haciendo una distinci\u00f3n entre las que son micro, peque\u00f1as y medianas.<\/p>\n<p style=\"font-weight: 400;\">Respecto de la medida, en su cuenta de Twitter el director de ARBA,\u00a0<strong>Cristian Girard<\/strong>, explic\u00f3:\u00a0<strong>\u201cEn el marco de la pandemia de COVID-19, y en virtud de la pol\u00edtica de aislamiento preventivo social y obligatorio, decidimos extender la vigencia del plan de pagos para pymes aprobado en el marco de la ley de emergencia sancionada en diciembre por la Legislatura\u201d<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Si bien subray\u00f3 que\u00a0<strong>\u201catravesamos hoy el embate de una pandemia\u201d<\/strong>, Girard hizo hincapi\u00e9 en que fueron\u00a0<strong>\u201clas pol\u00edticas econ\u00f3micas desplegadas por los gobiernos del PRO y sus aliados las que dejaron miles de pymes quebradas\u201d<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">En ese sentido, desde su cuenta @cristiangirard, destac\u00f3 que las empresas que\u00a0<strong>\u201clograron llegar activas a 2020 lo hicieron en situaci\u00f3n cr\u00edtica, acumulando deudas considerables con el fisco\u201d<\/strong>. El plan de pago de ARBA busca favorecer a esas pymes, de manera que\u00a0<strong>\u201ca medida que se vayan retomando actividades las empresas puedan acceder a los beneficios de la moratoria\u201d<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Condiciones del plan<\/strong><\/p>\n<p style=\"font-weight: 400;\">En el caso de las microempresas, no deben abonar anticipos y el capital puede ser financiado con tasas de entre 1,5% y 2,75%, seg\u00fan el plazo elegido. Las peque\u00f1as, en tanto, tienen que pagar anticipos que van del 5% al 15%, y cuentan con tasas de inter\u00e9s de entre 1,75% y 3%, de acuerdo a la cantidad de cuotas del plan. Por su parte, las medianas deben abonar un anticipo que var\u00eda del 5% al 20%, con tasas de inter\u00e9s de entre 2% y 3%.<\/p>\n<p style=\"font-weight: 400;\">La clasificaci\u00f3n de micro, peque\u00f1a y mediana empresa se realiza en funci\u00f3n de los par\u00e1metros que establece el Ministerio de Desarrollo Productivo de la Naci\u00f3n, que categoriza a las pymes teniendo en cuenta la actividad declarada, los montos de ventas anuales y la cantidad de empleados.<\/p>\n<p style=\"font-weight: 400;\">Si las empresas, cualquiera sea su clasificaci\u00f3n, optan por sumarse al programa de regularizaci\u00f3n pagando al contado o hasta en 3 cuotas, no abonan anticipos ni intereses de financiaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong>Adhesi\u00f3n web<\/strong><\/p>\n<p style=\"font-weight: 400;\">Para adherir al plan, las empresas tienen que registrarse previamente en el \u201cPrograma Buenos Aires ActiBA\u201d del Ministerio de Producci\u00f3n, Ciencia e Innovaci\u00f3n Tecnol\u00f3gica de la provincia de Buenos Aires o en el \u201cAgro Registro MiPyMES\u201d del Ministerio de Desarrollo Agrario bonaerense, seg\u00fan la actividad econ\u00f3mica que realicen.<\/p>\n<p style=\"font-weight: 400;\">Adem\u00e1s, deben tener presentadas a la fecha del acogimiento las declaraciones juradas del Impuesto sobre los Ingresos Brutos correspondientes al ejercicio fiscal 2019 y mantener estable su planta de personal durante la vigencia del r\u00e9gimen.<\/p>\n<p style=\"font-weight: 400;\">Una vez inscriptas en \u201cBuenos Aires ActiBA\u201d o \u201cAgro Registro MiPyMES\u201d, las empresas pueden suscribir el plan de pagos por internet, en la Agencia de Recaudaci\u00f3n, ingresando a\u00a0<em><a href=\"http:\/\/www.arba.gob.ar\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.arba.gob.ar\/&amp;source=gmail&amp;ust=1590769730976000&amp;usg=AFQjCNHham6IY0TqGOG9Z6m9rC_5SCKE3Q\">www.arba.gob.ar<\/a><\/em>.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>La Agencia de Recaudaci\u00f3n de la provincia de Buenos Aires extendi\u00f3 hasta el\u00a031 de julio pr\u00f3ximo\u00a0la vigencia del plan de regularizaci\u00f3n de deudas destinado a micro, peque\u00f1as y medianas empresas, que venc\u00eda el 31 de mayo. El programa de facilidades, que contempla la quita total de intereses, multas y punitorios, abarca deudas vencidas al 31 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48030,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52],"tags":[],"class_list":["post-49314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-28T16:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/03\/ARBA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses\",\"datePublished\":\"2020-05-28T16:53:46+00:00\",\"dateModified\":\"2020-05-28T16:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\"},\"wordCount\":664,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Comunidad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\",\"name\":\"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2020-05-28T16:53:46+00:00\",\"dateModified\":\"2020-05-28T16:53:46+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/","og_locale":"es_ES","og_type":"article","og_title":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2020-05-28T16:53:46+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/03\/ARBA.jpeg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses","datePublished":"2020-05-28T16:53:46+00:00","dateModified":"2020-05-28T16:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/"},"wordCount":664,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Comunidad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/","name":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2020-05-28T16:53:46+00:00","dateModified":"2020-05-28T16:53:46+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/05\/28\/arba-prorroga-por-dos-meses-el-plan-de-pago-con-beneficios-para-pymes-bonaerenses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"ARBA prorroga por dos meses el plan de pago con beneficios para pymes bonaerenses"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/49314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=49314"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/49314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/48030"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=49314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=49314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=49314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}