{"id":52839,"date":"2020-10-19T23:13:15","date_gmt":"2020-10-19T23:13:15","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=52839"},"modified":"2020-10-19T23:13:15","modified_gmt":"2020-10-19T23:13:15","slug":"bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/","title":{"rendered":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud"},"content":{"rendered":"<p>El intendente Sergio Bordoni dialog\u00f3 con CELTTV NOTICIAS y dej\u00f3 varios titulares vinculados al \u00e1rea de salud con designaci\u00f3n de nuevos funcionarios, ampliaci\u00f3n del Hospital Municipal y construcci\u00f3n de terminales de \u00f3mnibus para Tornquist y Sierra de la Ventana, entre otros temas.<\/p>\n<p>&#8220;Se va a ampliar el n\u00famero de camas para el sector de Covid-19 y, a su vez, se construir\u00e1 una terapia intensiva con capacidad para cinco personas. La ampliaci\u00f3n tendr\u00e1 60 M2 y contamos con la colaboraci\u00f3n de un particular para llevarla a cabo&#8221;, adelant\u00f3 Bordoni.<\/p>\n<p>&#8220;La provincia se encarga de enviarnos todo el equipo tecnol\u00f3gico para equipar la terapia intensiva e intermedia&#8221;, subray\u00f3.<\/p>\n<p>El jefe comunal tambi\u00e9n anunci\u00f3 novedades en el gabinete, con la designaci\u00f3n del doctor Daniel Barca como nuevo secretario de Salud y el doctor Diego Herrera, como Director del Hospital.<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"2020 10 19 SERGIO BORDONI VIA ZOOM\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/lIJXLtmlsL8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El intendente Sergio Bordoni dialog\u00f3 con CELTTV NOTICIAS y dej\u00f3 varios titulares vinculados al \u00e1rea de salud con designaci\u00f3n de nuevos funcionarios, ampliaci\u00f3n del Hospital Municipal y construcci\u00f3n de terminales de \u00f3mnibus para Tornquist y Sierra de la Ventana, entre otros temas. &#8220;Se va a ampliar el n\u00famero de camas para el sector de Covid-19 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52840,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,51,52],"tags":[],"class_list":["post-52839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-comunidad","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-19T23:13:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/10\/Sergio-Bordoni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1372\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud\",\"datePublished\":\"2020-10-19T23:13:15+00:00\",\"dateModified\":\"2020-10-19T23:13:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\"},\"wordCount\":169,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Comunidad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\",\"name\":\"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2020-10-19T23:13:15+00:00\",\"dateModified\":\"2020-10-19T23:13:15+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2020-10-19T23:13:15+00:00","og_image":[{"width":1372,"height":694,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/10\/Sergio-Bordoni.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud","datePublished":"2020-10-19T23:13:15+00:00","dateModified":"2020-10-19T23:13:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/"},"wordCount":169,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Comunidad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/","name":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2020-10-19T23:13:15+00:00","dateModified":"2020-10-19T23:13:15+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/10\/19\/bordoni-anuncio-la-construccion-de-una-terapia-intensiva-y-la-designacion-de-nuevas-autoridades-de-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Bordoni anunci\u00f3 la construcci\u00f3n de una terapia intensiva y la designaci\u00f3n de nuevas autoridades de salud"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=52839"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/52840"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=52839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=52839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=52839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}