{"id":53276,"date":"2020-11-09T13:17:42","date_gmt":"2020-11-09T13:17:42","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=53276"},"modified":"2020-11-09T13:17:42","modified_gmt":"2020-11-09T13:17:42","slug":"primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/","title":{"rendered":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito"},"content":{"rendered":"<p>La Secretar\u00eda de Salud del distrito de Tornquist inform\u00f3 que \u00e9ste lunes no se reportaron casos positivos de COVID19 en el distrito de Tornquist,<\/p>\n<p>Ahora los confirmados suman 422 de los cuales hay 14 activos y 401 recuperados. Hay 4 sospechosos, 431 descartados, 148 personas aisladas preventivamente y 7 fallecidas.<\/p>\n<p><a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=53277\" rel=\"attachment wp-att-53277\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-53277\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136.jpg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136.jpg 1080w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-300x300.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-1024x1024.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-150x150.jpg 150w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-768x768.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-75x75.jpg 75w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136-750x750.jpg 750w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Salud del distrito de Tornquist inform\u00f3 que \u00e9ste lunes no se reportaron casos positivos de COVID19 en el distrito de Tornquist, Ahora los confirmados suman 422 de los cuales hay 14 activos y 401 recuperados. Hay 4 sospechosos, 431 descartados, 148 personas aisladas preventivamente y 7 fallecidas.<\/p>\n","protected":false},"author":1,"featured_media":53277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52],"tags":[],"class_list":["post-53276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T13:17:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito\",\"datePublished\":\"2020-11-09T13:17:42+00:00\",\"dateModified\":\"2020-11-09T13:17:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Comunidad\",\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\",\"name\":\"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2020-11-09T13:17:42+00:00\",\"dateModified\":\"2020-11-09T13:17:42+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/","og_locale":"es_ES","og_type":"article","og_title":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2020-11-09T13:17:42+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/11\/136.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito","datePublished":"2020-11-09T13:17:42+00:00","dateModified":"2020-11-09T13:17:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/"},"wordCount":58,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Comunidad","Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/","name":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2020-11-09T13:17:42+00:00","dateModified":"2020-11-09T13:17:42+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/11\/09\/primer-dia-sin-que-se-registren-nuevos-casos-de-covid-en-el-distrito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Primer d\u00eda sin que se registren nuevos casos de COVID en el distrito"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53276"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53277"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}