{"id":53975,"date":"2020-12-06T15:06:39","date_gmt":"2020-12-06T15:06:39","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=53975"},"modified":"2020-12-06T15:06:39","modified_gmt":"2020-12-06T15:06:39","slug":"avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/","title":{"rendered":"Avanza en el parlamento el proyecto &#8220;Veteranos de Guerra Continentales de Malvinas&#8221;"},"content":{"rendered":"<div>Con la presencia de ex-conscriptos de Tornquist y la regi\u00f3n que estuvieron bajo bandera en el continente durante el conflicto b\u00e9lico desarrollado en las Islas Malvinas entre el 2 de abril y el 14 de junio, se realiz\u00f3 una reuni\u00f3n informativa a cargo de Eduardo Pagella, en instalaciones de la Asociaci\u00f3n Espa\u00f1ola.<\/div>\n<div>Los entonces conscriptos que estuvieron en el continente a disposici\u00f3n de las autoridades del momento para ser embarcados rumbo a las islas, hoy piden un reconocimiento por parte del Estado Nacional, a trav\u00e9s de un proyecto que fue elevado oportunamente a las autoridades nacionales y, actualmente, avanza en el parlamento.<\/div>\n<div>La iniciativa tiene como objetivo solicitar un reconocimiento hist\u00f3rico a aquellos ciudadanos, entonces j\u00f3venes conscriptos de todo el pa\u00eds, quienes fueron convocados y movilizados bajo el mando militar, y que a pesar de no haber sido destinados en el Teatro de Operaciones Malvinas o entrado en combate en el \u00e1rea del Teatro de Operaciones del Atl\u00e1ntico Sur, fueron afectados a realizar las innumerables tareas que son necesarias en una guerra, entre el 2 de abril y el 14 de junio de 1982.<\/div>\n<div>Dichos soldados conscriptos, si bien permanecieron en el continente, se encontraban bajo el C\u00f3digo de Justicia Militar y a disposici\u00f3n absoluta ante eventuales traslados y la realizaci\u00f3n de acciones indispensables tales como abastecimiento de municiones, vigilancia de los polvorines y cuarteles, tareas en comunicaciones, artiller\u00eda, etc., en diferentes puntos del continente.<\/div>\n<div>Uno de los responsables del proyecto es Eduardo Pagella, el cual brind\u00f3 detalles del alcance del proyecto y de la gran expectativa que existe ante el avance del mismo dentro del parlamento.<\/div>\n<div>https:\/\/www.youtube.com\/watch?v=y7WQEGh6QgU<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=53977\" rel=\"attachment wp-att-53977\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-53977\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8.jpg 1280w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8-300x225.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8-1024x768.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8-768x576.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8-750x563.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8-1140x855.jpg 1140w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=53976\" rel=\"attachment wp-att-53976\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-53976\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb.jpg 1280w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb-300x225.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb-1024x768.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb-768x576.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb-750x563.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/477dae46-57e6-4650-b75e-4dbfcc346edb-1140x855.jpg 1140w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a> <a href=\"http:\/\/www.celttv.com.ar\/?attachment_id=53978\" rel=\"attachment wp-att-53978\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-53978\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a.jpg\" alt=\"\" width=\"1280\" height=\"960\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a.jpg 1280w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a-300x225.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a-1024x768.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a-768x576.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a-750x563.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/f3d4fba8-39c0-4846-81fc-e11d80dac74a-1140x855.jpg 1140w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con la presencia de ex-conscriptos de Tornquist y la regi\u00f3n que estuvieron bajo bandera en el continente durante el conflicto b\u00e9lico desarrollado en las Islas Malvinas entre el 2 de abril y el 14 de junio, se realiz\u00f3 una reuni\u00f3n informativa a cargo de Eduardo Pagella, en instalaciones de la Asociaci\u00f3n Espa\u00f1ola. Los entonces conscriptos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-53975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avanza en el parlamento el proyecto &quot;Veteranos de Guerra Continentales de Malvinas&quot; - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avanza en el parlamento el proyecto &quot;Veteranos de Guerra Continentales de Malvinas&quot; - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-06T15:06:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Avanza en el parlamento el proyecto &#8220;Veteranos de Guerra Continentales de Malvinas&#8221;\",\"datePublished\":\"2020-12-06T15:06:39+00:00\",\"dateModified\":\"2020-12-06T15:06:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Destacadas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\",\"name\":\"Avanza en el parlamento el proyecto \\\"Veteranos de Guerra Continentales de Malvinas\\\" - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2020-12-06T15:06:39+00:00\",\"dateModified\":\"2020-12-06T15:06:39+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avanza en el parlamento el proyecto &#8220;Veteranos de Guerra Continentales de Malvinas&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avanza en el parlamento el proyecto \"Veteranos de Guerra Continentales de Malvinas\" - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/","og_locale":"es_ES","og_type":"article","og_title":"Avanza en el parlamento el proyecto \"Veteranos de Guerra Continentales de Malvinas\" - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2020-12-06T15:06:39+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2020\/12\/ceb5e98c-2051-4e33-90c6-2bd3601597a8.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Avanza en el parlamento el proyecto &#8220;Veteranos de Guerra Continentales de Malvinas&#8221;","datePublished":"2020-12-06T15:06:39+00:00","dateModified":"2020-12-06T15:06:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/"},"wordCount":298,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Destacadas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/","name":"Avanza en el parlamento el proyecto \"Veteranos de Guerra Continentales de Malvinas\" - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2020-12-06T15:06:39+00:00","dateModified":"2020-12-06T15:06:39+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2020\/12\/06\/avanza-en-el-parlamento-el-proyecto-veteranos-de-guerra-continentales-de-malvinas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Avanza en el parlamento el proyecto &#8220;Veteranos de Guerra Continentales de Malvinas&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=53975"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/53975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/53977"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=53975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=53975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=53975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}