{"id":60507,"date":"2021-09-29T14:37:44","date_gmt":"2021-09-29T14:37:44","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=60507"},"modified":"2021-09-29T14:37:44","modified_gmt":"2021-09-29T14:37:44","slug":"secuestran-droga-dinero-y-un-arma-en-tornquist","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/","title":{"rendered":"Secuestran droga, dinero y un arma en Tornquist"},"content":{"rendered":"\n<p>La polic\u00eda secuestr\u00f3 una importante cantidad de droga, dinero y un arma de fuego en Tornquist. Y hubo dos detenidos.<\/p>\n\n\n\n<p>Seg\u00fan indicaron fuentes consultadas por&nbsp;<strong>LA BR\u00daJULA 24<\/strong>, una investigaci\u00f3n realizada entre los uniformados y la fiscal\u00eda a cargo de Mauricio Del Cero permiti\u00f3 obtener \u00f3rdenes de allanamiento para dos domicilios de la vecina localidad.<\/p>\n\n\n\n<p>Uno de ellos se llev\u00f3 adelante en calle Independencia 634, donde reside Ren\u00e9 Ort\u00edz, y el restante en Rodolfo Scharff 535, donde vive Mart\u00edn Andr\u00e9s Ricciardi. All\u00ed encontraron una gran cantidad de coca\u00edna, marihuana, elementos de corte y pesaje, un arma de fuego y una suma de dinero en efectivo que supera un mill\u00f3n de pesos.<\/p>\n\n\n\n<p><strong>Por consiguiente, fueron detenidos Mart\u00edn Ricciardi y su concubina, Camila Ayel\u00e9n Rossini.<\/strong><\/p>\n\n\n\n<p><strong>FUENTE<\/strong>: La Br\u00fajula 24<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-1024x614.jpg\" alt=\"\" class=\"wp-image-60508\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-1024x614.jpg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-300x180.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-768x461.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-750x450.jpg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7-1140x684.jpg 1140w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"2021 09 29 EZEQUIEL GABELLA   ALLANAMIENTO EN TORNQUIST\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Mp-TgFlME4c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda secuestr\u00f3 una importante cantidad de droga, dinero y un arma de fuego en Tornquist. Y hubo dos detenidos. Seg\u00fan indicaron fuentes consultadas por&nbsp;LA BR\u00daJULA 24, una investigaci\u00f3n realizada entre los uniformados y la fiscal\u00eda a cargo de Mauricio Del Cero permiti\u00f3 obtener \u00f3rdenes de allanamiento para dos domicilios de la vecina localidad. Uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":60508,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,51,52,61],"tags":[],"class_list":["post-60507","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-comunidad","category-destacadas","category-policiales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Secuestran droga, dinero y un arma en Tornquist - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secuestran droga, dinero y un arma en Tornquist - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-29T14:37:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Secuestran droga, dinero y un arma en Tornquist\",\"datePublished\":\"2021-09-29T14:37:44+00:00\",\"dateModified\":\"2021-09-29T14:37:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Comunidad\",\"Destacadas\",\"Policiales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\",\"name\":\"Secuestran droga, dinero y un arma en Tornquist - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2021-09-29T14:37:44+00:00\",\"dateModified\":\"2021-09-29T14:37:44+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secuestran droga, dinero y un arma en Tornquist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secuestran droga, dinero y un arma en Tornquist - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/","og_locale":"es_ES","og_type":"article","og_title":"Secuestran droga, dinero y un arma en Tornquist - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2021-09-29T14:37:44+00:00","og_image":[{"width":1200,"height":720,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2021\/09\/ad829273-304e-4aef-b03a-c2740ecd16d7.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Secuestran droga, dinero y un arma en Tornquist","datePublished":"2021-09-29T14:37:44+00:00","dateModified":"2021-09-29T14:37:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/"},"wordCount":150,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Comunidad","Destacadas","Policiales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/","name":"Secuestran droga, dinero y un arma en Tornquist - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2021-09-29T14:37:44+00:00","dateModified":"2021-09-29T14:37:44+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2021\/09\/29\/secuestran-droga-dinero-y-un-arma-en-tornquist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Secuestran droga, dinero y un arma en Tornquist"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/60507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=60507"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/60507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/60508"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=60507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=60507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=60507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}