{"id":65485,"date":"2022-04-23T19:46:27","date_gmt":"2022-04-23T19:46:27","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=65485"},"modified":"2022-04-23T19:46:27","modified_gmt":"2022-04-23T19:46:27","slug":"victoria-de-las-lobas-en-sub-14-sobre-el-nacional","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/","title":{"rendered":"Victoria de &#8220;Las Lobas&#8221; en Sub-14 sobre El Nacional"},"content":{"rendered":"\n<p>Con una victoria contundente, Las Lobas vencieron al equipo Sub-14 de El Nacional, en partido correspondiente a la fecha N\u00ba 3 del Torneo Apertura  de la Asociaci\u00f3n  Bahiense de Hockey.<\/p>\n\n\n<p>El partido se desarroll\u00f2 en cancha del Club Uni\u00f3n, donde el eqipo bahiense cay\u00f3 goleado por &#8220;Las Lobas&#8221; por 5 a 0, con goles marcados por Juanita Camargo Bauer (2), Aylen Kloster, Shadia Del Rio y Martina Rojas.<\/p>\n\n\n<p>La pr\u00f3xima fecha Uni\u00f3n (T) ser\u00e1 de visitante ante el Club La Armonia.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"540\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n.jpg\" alt=\"\" class=\"wp-image-65486\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n.jpg 810w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n-300x200.jpg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n-768x512.jpg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n-750x500.jpg 750w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con una victoria contundente, Las Lobas vencieron al equipo Sub-14 de El Nacional, en partido correspondiente a la fecha N\u00ba 3 del Torneo Apertura de la Asociaci\u00f3n Bahiense de Hockey. El partido se desarroll\u00f2 en cancha del Club Uni\u00f3n, donde el eqipo bahiense cay\u00f3 goleado por &#8220;Las Lobas&#8221; por 5 a 0, con goles marcados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":65486,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,60,62,52,63],"tags":[],"class_list":["post-65485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celt-tv-noticias","category-deporte","category-deportes","category-destacadas","category-magazine-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Victoria de &quot;Las Lobas&quot; en Sub-14 sobre El Nacional - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Victoria de &quot;Las Lobas&quot; en Sub-14 sobre El Nacional - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-23T19:46:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ulises\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ulises\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\"},\"author\":{\"name\":\"ulises\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\"},\"headline\":\"Victoria de &#8220;Las Lobas&#8221; en Sub-14 sobre El Nacional\",\"datePublished\":\"2022-04-23T19:46:27+00:00\",\"dateModified\":\"2022-04-23T19:46:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\"},\"wordCount\":90,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"articleSection\":[\"Celt TV Noticias\",\"Deporte\",\"Deportes\",\"Destacadas\",\"Magazine Sport\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\",\"name\":\"Victoria de \\\"Las Lobas\\\" en Sub-14 sobre El Nacional - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2022-04-23T19:46:27+00:00\",\"dateModified\":\"2022-04-23T19:46:27+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Victoria de &#8220;Las Lobas&#8221; en Sub-14 sobre El Nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace\",\"name\":\"ulises\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g\",\"caption\":\"ulises\"},\"sameAs\":[\"http:\/\/www.celttv.com.ar\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Victoria de \"Las Lobas\" en Sub-14 sobre El Nacional - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Victoria de \"Las Lobas\" en Sub-14 sobre El Nacional - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2022-04-23T19:46:27+00:00","og_image":[{"width":810,"height":540,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/04\/278688194_5434731486540097_1461703573564340008_n.jpg","type":"image\/jpeg"}],"author":"ulises","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ulises"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/"},"author":{"name":"ulises","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace"},"headline":"Victoria de &#8220;Las Lobas&#8221; en Sub-14 sobre El Nacional","datePublished":"2022-04-23T19:46:27+00:00","dateModified":"2022-04-23T19:46:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/"},"wordCount":90,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"articleSection":["Celt TV Noticias","Deporte","Deportes","Destacadas","Magazine Sport"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/","name":"Victoria de \"Las Lobas\" en Sub-14 sobre El Nacional - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2022-04-23T19:46:27+00:00","dateModified":"2022-04-23T19:46:27+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2022\/04\/23\/victoria-de-las-lobas-en-sub-14-sobre-el-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"Victoria de &#8220;Las Lobas&#8221; en Sub-14 sobre El Nacional"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/6d99c072dba59953809c81446e9d0ace","name":"ulises","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f2c48bdc33b30088f941fb6082e555f2874c98e20cb159d7b92b50eadfce793?s=96&d=mm&r=g","caption":"ulises"},"sameAs":["http:\/\/www.celttv.com.ar"]}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=65485"}],"version-history":[{"count":0,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/65485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/65486"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=65485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=65485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=65485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}