{"id":74810,"date":"2023-04-03T17:34:45","date_gmt":"2023-04-03T20:34:45","guid":{"rendered":"http:\/\/www.celttv.com.ar\/?p=74810"},"modified":"2023-04-03T17:34:45","modified_gmt":"2023-04-03T20:34:45","slug":"el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana","status":"publish","type":"post","link":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/","title":{"rendered":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana"},"content":{"rendered":"<p>Mediante una conferencia de prensa, el intendente municipal Sergio Bordoni puso en funciones a Julio Baamonde; quien reemplazar\u00e1 a Hugo Polvara, que por motivos personales se alejar\u00e1 del cargo que asumi\u00f3 en diciembre de 2015.<\/p>\n<p>Acompa\u00f1ado por la Secretar\u00eda de Hacienda, Estefania Bordoni y el Secretario de Gobierno y Seguridad, Ezequiel Gabella; el jefe comunal expres\u00f3 su contento por sumar a Baamonde al equipo de gobierno, para continuar llevando adelante las distintas tareas y alcanzar los distintos objetivos propuestos para la localidad de Sierra de la Ventana.<\/p>\n<p>Bordoni agradeci\u00f3 a Polvara por la labor realizada durante estos siete a\u00f1os al frente de la delegaci\u00f3n, destacando su compromiso con la comunidad y su trabajo en pos del crecimiento de la localidad y del mejoramiento de la calidad de vida de los residentes y turistas que suelen visitarla.<\/p>\n<p>Es importante mencionar, que la delegaci\u00f3n cuenta con un equipo de trabajo, integrado por la Directora de Gobierno, Graciela Bagu; y la Ing.Gisela Lencina, de la Secretar\u00eda de Obras y Servicios\u00a0P\u00fablicos; con el objetivo de llevar adelante todas la metas propuestas, y dar respuestas a los ciudadanos en una localidad que ha crecido exponencialmente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-74811\" src=\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-300x176.jpeg\" alt=\"\" width=\"300\" height=\"176\" srcset=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-300x176.jpeg 300w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-1024x600.jpeg 1024w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-768x450.jpeg 768w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-750x440.jpeg 750w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium-1140x668.jpeg 1140w, https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium.jpeg 1310w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante una conferencia de prensa, el intendente municipal Sergio Bordoni puso en funciones a Julio Baamonde; quien reemplazar\u00e1 a Hugo Polvara, que por motivos personales se alejar\u00e1 del cargo que asumi\u00f3 en diciembre de 2015. Acompa\u00f1ado por la Secretar\u00eda de Hacienda, Estefania Bordoni y el Secretario de Gobierno y Seguridad, Ezequiel Gabella; el jefe comunal [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":74811,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,52,59],"tags":[788],"class_list":["post-74810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","category-destacadas","category-municipales","tag-el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV<\/title>\n<meta name=\"description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV\" \/>\n<meta property=\"og:description\" content=\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\" \/>\n<meta property=\"og:site_name\" content=\"CELTTV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/celtTV\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-03T20:34:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1310\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Herrada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Herrada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\"},\"author\":{\"name\":\"Miguel Herrada\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/9059dc91dc7204ef4182cdb65225f07d\"},\"headline\":\"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana\",\"datePublished\":\"2023-04-03T20:34:45+00:00\",\"dateModified\":\"2023-04-03T20:34:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"keywords\":[\"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana\"],\"articleSection\":[\"Comunidad\",\"Destacadas\",\"Municipales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\",\"url\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\",\"name\":\"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV\",\"isPartOf\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#website\"},\"datePublished\":\"2023-04-03T20:34:45+00:00\",\"dateModified\":\"2023-04-03T20:34:45+00:00\",\"description\":\"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.celttv.com.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.celttv.com.ar\/#website\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"name\":\"CELTTV\",\"description\":\"Cooperativa El\u00e9ctrica de Tornquist\",\"publisher\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.celttv.com.ar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.celttv.com.ar\/#organization\",\"name\":\"CELTTV\",\"url\":\"https:\/\/www.celttv.com.ar\/\",\"sameAs\":[\"https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg\",\"https:\/\/www.facebook.com\/celtTV\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"contentUrl\":\"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png\",\"width\":461,\"height\":159,\"caption\":\"CELTTV\"},\"image\":{\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/9059dc91dc7204ef4182cdb65225f07d\",\"name\":\"Miguel Herrada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/67724d5b3c716623ffd76bec7e45841a442ac3b456e914dbba90b0fad2b8e0b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/67724d5b3c716623ffd76bec7e45841a442ac3b456e914dbba90b0fad2b8e0b1?s=96&d=mm&r=g\",\"caption\":\"Miguel Herrada\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/","og_locale":"es_ES","og_type":"article","og_title":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV","og_description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","og_url":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/","og_site_name":"CELTTV","article_publisher":"https:\/\/www.facebook.com\/celtTV\/","article_published_time":"2023-04-03T20:34:45+00:00","og_image":[{"width":1310,"height":768,"url":"https:\/\/www.celttv.com.ar\/wp-content\/uploads\/2023\/04\/delegadosv-Medium.jpeg","type":"image\/jpeg"}],"author":"Miguel Herrada","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Miguel Herrada","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#article","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/"},"author":{"name":"Miguel Herrada","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/9059dc91dc7204ef4182cdb65225f07d"},"headline":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana","datePublished":"2023-04-03T20:34:45+00:00","dateModified":"2023-04-03T20:34:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/"},"wordCount":211,"publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"keywords":["El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana"],"articleSection":["Comunidad","Destacadas","Municipales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/","url":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/","name":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana - CELTTV","isPartOf":{"@id":"https:\/\/www.celttv.com.ar\/#website"},"datePublished":"2023-04-03T20:34:45+00:00","dateModified":"2023-04-03T20:34:45+00:00","description":"Sitio web de noticias de la localidad de Tornquist, provincia de Buenos Aires, Rep\u00fablica Argentina. Contenido propio originado por periodistas de CELTTV, el canal de TV local de la Cooperativa El\u00e9ctrica de Tornquist. Turismo, Pol\u00edtica, Sociedad, Deporte, Cultura y todo el contenido de inter\u00e9s general que la gente del pueblo y la regi\u00f3n debe conocer.","breadcrumb":{"@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.celttv.com.ar\/index.php\/2023\/04\/03\/el-intendente-designo-un-nuevo-delegado-en-sierra-de-la-ventana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.celttv.com.ar\/"},{"@type":"ListItem","position":2,"name":"El intendente design\u00f3 un nuevo delegado en Sierra de la Ventana"}]},{"@type":"WebSite","@id":"https:\/\/www.celttv.com.ar\/#website","url":"https:\/\/www.celttv.com.ar\/","name":"CELTTV","description":"Cooperativa El\u00e9ctrica de Tornquist","publisher":{"@id":"https:\/\/www.celttv.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.celttv.com.ar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.celttv.com.ar\/#organization","name":"CELTTV","url":"https:\/\/www.celttv.com.ar\/","sameAs":["https:\/\/www.youtube.com\/channel\/UCz_oIt8Hig64Ub-EmcNPIhg","https:\/\/www.facebook.com\/celtTV\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/","url":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","contentUrl":"http:\/\/www.celttv.com.ar\/wp-content\/uploads\/2022\/08\/logo-1.png","width":461,"height":159,"caption":"CELTTV"},"image":{"@id":"https:\/\/www.celttv.com.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/9059dc91dc7204ef4182cdb65225f07d","name":"Miguel Herrada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.celttv.com.ar\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/67724d5b3c716623ffd76bec7e45841a442ac3b456e914dbba90b0fad2b8e0b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/67724d5b3c716623ffd76bec7e45841a442ac3b456e914dbba90b0fad2b8e0b1?s=96&d=mm&r=g","caption":"Miguel Herrada"}}]}},"_links":{"self":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=74810"}],"version-history":[{"count":1,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74810\/revisions"}],"predecessor-version":[{"id":74812,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/74810\/revisions\/74812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media\/74811"}],"wp:attachment":[{"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=74810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=74810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.celttv.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=74810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}